{"id":90,"count":3,"description":"","link":"https:\/\/alps.edu\/es\/fees\/780-4-weeks\/","name":"$780 - 4 semanas","slug":"780-4-semanas","taxonomy":"fees","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>$780 - 4 weeks Archives - ALPS Language School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alps.edu\/es\/honorarios\/780-4-semanas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"$780 - 4 weeks Archives - ALPS Language School\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alps.edu\/es\/honorarios\/780-4-semanas\/\" \/>\n<meta property=\"og:site_name\" content=\"ALPS Language School\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ALPS_School\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alps.edu\\\/fees\\\/780-4-weeks\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/fees\\\/780-4-weeks\\\/\",\"name\":\"$780 - 4 weeks Archives - ALPS Language School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/fees\\\/780-4-weeks\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alps.edu\\\/fees\\\/780-4-weeks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alps.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"$780 - 4 weeks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"name\":\"ALPS Language School\",\"description\":\"Seattle English Classes for Adults\",\"publisher\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alps.edu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\",\"name\":\"ALPS Language School\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"contentUrl\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"width\":256,\"height\":181,\"caption\":\"ALPS Language School\"},\"image\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ALPS.Language.School\\\/\",\"https:\\\/\\\/x.com\\\/ALPS_School\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/alps-language-school\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"$780 - 4 weeks Archives - ALPS Language School","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alps.edu\/es\/honorarios\/780-4-semanas\/","og_locale":"es_MX","og_type":"article","og_title":"$780 - 4 weeks Archives - ALPS Language School","og_url":"https:\/\/alps.edu\/es\/honorarios\/780-4-semanas\/","og_site_name":"ALPS Language School","twitter_card":"summary_large_image","twitter_site":"@ALPS_School","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alps.edu\/fees\/780-4-weeks\/","url":"https:\/\/alps.edu\/fees\/780-4-weeks\/","name":"$780 - 4 semanas Archivo - Escuela de Idiomas ALPS","isPartOf":{"@id":"https:\/\/alps.edu\/#website"},"breadcrumb":{"@id":"https:\/\/alps.edu\/fees\/780-4-weeks\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/alps.edu\/fees\/780-4-weeks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alps.edu\/"},{"@type":"ListItem","position":2,"name":"$780 - 4 weeks"}]},{"@type":"WebSite","@id":"https:\/\/alps.edu\/#website","url":"https:\/\/alps.edu\/","name":"ALPS Language School","description":"Clases de ingl\u00e9s en Seattle para adultos","publisher":{"@id":"https:\/\/alps.edu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alps.edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alps.edu\/#organization","name":"ALPS Language School","url":"https:\/\/alps.edu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/","url":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","contentUrl":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","width":256,"height":181,"caption":"ALPS Language School"},"image":{"@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ALPS.Language.School\/","https:\/\/x.com\/ALPS_School","https:\/\/www.linkedin.com\/school\/alps-language-school\/"]}]}},"_links":{"self":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/fees\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/fees"}],"about":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/taxonomies\/fees"}],"wp:post_type":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/course?fees=90"},{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/mec-events?fees=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}