{"id":925,"date":"2020-07-28T12:55:43","date_gmt":"2020-07-28T19:55:43","guid":{"rendered":"https:\/\/alps.edu\/?page_id=925"},"modified":"2020-07-28T13:54:24","modified_gmt":"2020-07-28T20:54:24","slug":"calendario","status":"publish","type":"page","link":"https:\/\/alps.edu\/es\/calendar\/","title":{"rendered":"Calendario"},"content":{"rendered":"<div id=\"mec_skin_202\" class=\"mec-wrap colorskin-custom   mec-full-calendar-wrap\">\r\n\r\n    <div class=\"mec-search-form mec-totalcal-box\">\r\n                                    <div id=\"mec_search_form_202\" class=\"\">\r\n\r\n            \r\n            <div class=\"mec-dropdown-wrap\">\r\n                                                                                                            <\/div>\r\n        <\/div>\r\n        <div id=\"mec_search_form_202\">\r\n                                <\/div>\r\n        <div id=\"mec_search_form_202\" class=\"mec-full-calendar-search-ends\">\r\n                            <div class=\"mec-text-input-search\"><i class=\"mec-sl-magnifier\"><\/i>\r\n                    <input type=\"search\" value=\"\" id=\"mec_sf_s_202\" placeholder=\"\" \/>\r\n                <\/div>                                        <div class=\"mec-date-search\"><input type=\"hidden\" id=\"mec-filter-none\" value=\"Select\"><i class=\"mec-sl-calendar\"><\/i>\r\n                    <select id=\"mec_sf_month_202\">\r\n                        <option value=\"\">Seleccione mes<\/option><option value=\"01\">enero<\/option><option value=\"02\">febrero<\/option><option value=\"03\">marzo<\/option><option value=\"04\">abril<\/option><option value=\"05\">mayonesa<\/option><option value=\"06\">junio<\/option><option value=\"07\">julio<\/option><option value=\"08\">agosto<\/option><option value=\"09\">septiembre<\/option><option value=\"10\">octubre<\/option><option value=\"11\">noviembre<\/option><option value=\"12\">diciembre<\/option><\/select><select id=\"mec_sf_year_202\"><option value=\"2020\">2020<\/option><option value=\"2021\">2021<\/option><option value=\"2022\">2022<\/option><option value=\"2023\">2023<\/option><option value=\"2024\">2024<\/option><option value=\"2025\">2025<\/option><option value=\"2026\" selected>2026<\/option><option value=\"2027\">2027<\/option><option value=\"2028\">2028<\/option><option value=\"2029\">2029<\/option><option value=\"2030\">2030<\/option><\/select><\/div>                                                <div class=\"col-md-12 mec-tab-loader\">\r\n                <div class=\"mec-totalcal-view\">\r\n                                        <span class=\"mec-totalcal-monthlyview mec-totalcalview-selected\" data-skin=\"monthly\">Mensual<\/span>                    <span class=\"mec-totalcal-weeklyview\" data-skin=\"weekly\">Semanalmente<\/span>                    <span class=\"mec-totalcal-dailyview\" data-skin=\"daily\">A diario<\/span>                    <span class=\"mec-totalcal-listview\" data-skin=\"list\">Lista<\/span>                                                        <\/div>\r\n            <\/div>\r\n        <\/div>\r\n            <\/div>\r\n\r\n    <div id=\"mec_full_calendar_container_202\" class=\"mec-full-calendar-skin-container\">\r\n        <div id=\"mec_skin_202\" class=\"mec-wrap colorskin-custom\">\r\n\r\n    \r\n    <div class=\"mec-calendar\">\r\n        <div class=\"mec-calendar-topsec\">        <div class=\"mec-calendar-side mec-clear\">\r\n                        <div class=\"mec-skin-monthly-view-month-navigator-container\">\r\n                <div class=\"mec-month-navigator\" id=\"mec_month_navigator_202_202605\"><div class=\"mec-previous-month mec-load-month mec-previous-month\" data-mec-year=\"2026\" data-mec-month=\"04\"><a href=\"#\" class=\"mec-load-month-link\"><i class=\"mec-sl-angle-left\"><\/i> abril<\/a><\/div><div class=\"mec-calendar-header\"><h2>mayo 2026<\/h2><\/div><div class=\"mec-next-month mec-load-month mec-next-month\" data-mec-year=\"2026\" data-mec-month=\"06\"><a href=\"#\" class=\"mec-load-month-link\">junio <i class=\"mec-sl-angle-right\"><\/i><\/a><\/div><\/div>\r\n            <\/div>\r\n            \r\n            <div class=\"mec-calendar-table\" id=\"mec_skin_events_202\">\r\n                <div class=\"mec-month-container mec-month-container-selected\" id=\"mec_monthly_view_month_202_202605\" data-month-id=\"202605\"><dl class=\"mec-calendar-table-head\"><dt class=\"mec-calendar-day-head\">SU<\/dt><dt class=\"mec-calendar-day-head\">mes<\/dt><dt class=\"mec-calendar-day-head\">TU<\/dt><dt class=\"mec-calendar-day-head\">NOSOTROS<\/dt><dt class=\"mec-calendar-day-head\">EL<\/dt><dt class=\"mec-calendar-day-head\">FR<\/dt><dt class=\"mec-calendar-day-head\">SA<\/dt><\/dl><dl class=\"mec-calendar-row\">\r\n    <dt class=\"mec-table-nullday\">26<\/dt><dt class=\"mec-table-nullday\">27<\/dt><dt class=\"mec-table-nullday\">28<\/dt><dt class=\"mec-table-nullday\">29<\/dt><dt class=\"mec-table-nullday\">30<\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260501\" data-day=\"1\" data-month=\"202605\">1<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260502\" data-day=\"2\" data-month=\"202605\">2<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day\" data-mec-cell=\"20260503\" data-day=\"3\" data-month=\"202605\">3<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260504\" data-day=\"4\" data-month=\"202605\">4<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260505\" data-day=\"5\" data-month=\"202605\">5<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260506\" data-day=\"6\" data-month=\"202605\">6<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260507\" data-day=\"7\" data-month=\"202605\">7<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260508\" data-day=\"8\" data-month=\"202605\">8<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260509\" data-day=\"9\" data-month=\"202605\">9<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day\" data-mec-cell=\"20260510\" data-day=\"10\" data-month=\"202605\">10<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260511\" data-day=\"11\" data-month=\"202605\">11<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260512\" data-day=\"12\" data-month=\"202605\">12<\/dt><\/dt><dt class=\"mec-calendar-day  mec-selected-day\" data-mec-cell=\"20260513\" data-day=\"13\" data-month=\"202605\">13<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260514\" data-day=\"14\" data-month=\"202605\">14<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260515\" data-day=\"15\" data-month=\"202605\">15<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260516\" data-day=\"16\" data-month=\"202605\">16<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day\" data-mec-cell=\"20260517\" data-day=\"17\" data-month=\"202605\">17<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260518\" data-day=\"18\" data-month=\"202605\">18<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260519\" data-day=\"19\" data-month=\"202605\">19<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260520\" data-day=\"20\" data-month=\"202605\">20<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260521\" data-day=\"21\" data-month=\"202605\">21<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260522\" data-day=\"22\" data-month=\"202605\">22<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260523\" data-day=\"23\" data-month=\"202605\">23<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day\" data-mec-cell=\"20260524\" data-day=\"24\" data-month=\"202605\">24<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260525\" data-day=\"25\" data-month=\"202605\">25<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260526\" data-day=\"26\" data-month=\"202605\">26<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260527\" data-day=\"27\" data-month=\"202605\">27<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260528\" data-day=\"28\" data-month=\"202605\">28<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260529\" data-day=\"29\" data-month=\"202605\">29<\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260530\" data-day=\"30\" data-month=\"202605\">30<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day\" data-mec-cell=\"20260531\" data-day=\"31\" data-month=\"202605\">31<\/dt><\/dt><dt class=\"mec-table-nullday\">1<\/dt><dt class=\"mec-table-nullday\">2<\/dt><dt class=\"mec-table-nullday\">3<\/dt><dt class=\"mec-table-nullday\">4<\/dt><dt class=\"mec-table-nullday\">5<\/dt><dt class=\"mec-table-nullday\">6<\/dt><\/dl>\r\n<\/div>\r\n            <\/div>\r\n\r\n                    <\/div>\r\n        <div class=\"mec-calendar-events-side mec-clear\"><div class=\"mec-month-side\" id=\"mec_month_side_202_202605\"><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260501\" data-mec-cell=\"20260501\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Primero<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260502\" data-mec-cell=\"20260502\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 2do<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260503\" data-mec-cell=\"20260503\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Tercero<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260504\" data-mec-cell=\"20260504\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Cuarto<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260505\" data-mec-cell=\"20260505\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Quinto<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260506\" data-mec-cell=\"20260506\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Sexto<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260507\" data-mec-cell=\"20260507\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> S\u00e9ptimo<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260508\" data-mec-cell=\"20260508\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Octavo<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260509\" data-mec-cell=\"20260509\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Noveno<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260510\" data-mec-cell=\"20260510\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> D\u00e9cimo<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260511\" data-mec-cell=\"20260511\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 11\u00ba<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260512\" data-mec-cell=\"20260512\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 12\u00ba<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260513\" data-mec-cell=\"20260513\" style=\"display: block\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 13<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260514\" data-mec-cell=\"20260514\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 14<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260515\" data-mec-cell=\"20260515\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 15<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260516\" data-mec-cell=\"20260516\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 16 \u00b0<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260517\" data-mec-cell=\"20260517\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 17<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260518\" data-mec-cell=\"20260518\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 18<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260519\" data-mec-cell=\"20260519\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 19<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260520\" data-mec-cell=\"20260520\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> Vig\u00e9simo<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260521\" data-mec-cell=\"20260521\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 21<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260522\" data-mec-cell=\"20260522\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 22<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260523\" data-mec-cell=\"20260523\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 23<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260524\" data-mec-cell=\"20260524\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 24<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260525\" data-mec-cell=\"20260525\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 25<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260526\" data-mec-cell=\"20260526\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 26<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260527\" data-mec-cell=\"20260527\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 27<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260528\" data-mec-cell=\"20260528\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 28<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260529\" data-mec-cell=\"20260529\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 29<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260530\" data-mec-cell=\"20260530\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 30<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-202-20260531\" data-mec-cell=\"20260531\"><h6 class=\"mec-table-side-title\">Eventos para mayo<\/h6><h3 class=\"mec-color mec-table-side-day\"> 31<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><\/div><\/div><\/div><div class=\"mec-event-footer\"><\/div>    <\/div>\r\n\r\n<\/div>    <\/div>\r\n\r\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-925","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calendar - ALPS Language School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alps.edu\/es\/calendario\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calendar - ALPS Language School\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alps.edu\/es\/calendario\/\" \/>\n<meta property=\"og:site_name\" content=\"ALPS Language School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ALPS.Language.School\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-28T20:54:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ALPS_School\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alps.edu\\\/calendar\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/calendar\\\/\",\"name\":\"Calendar - ALPS Language School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\"},\"datePublished\":\"2020-07-28T19:55:43+00:00\",\"dateModified\":\"2020-07-28T20:54:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/calendar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alps.edu\\\/calendar\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alps.edu\\\/calendar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alps.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"name\":\"ALPS Language School\",\"description\":\"Seattle English Classes for Adults\",\"publisher\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alps.edu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\",\"name\":\"ALPS Language School\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"contentUrl\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"width\":256,\"height\":181,\"caption\":\"ALPS Language School\"},\"image\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ALPS.Language.School\\\/\",\"https:\\\/\\\/x.com\\\/ALPS_School\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/alps-language-school\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calendario - Escuela de idiomas ALPS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alps.edu\/es\/calendario\/","og_locale":"es_MX","og_type":"article","og_title":"Calendar - ALPS Language School","og_url":"https:\/\/alps.edu\/es\/calendario\/","og_site_name":"ALPS Language School","article_publisher":"https:\/\/www.facebook.com\/ALPS.Language.School\/","article_modified_time":"2020-07-28T20:54:24+00:00","twitter_card":"summary_large_image","twitter_site":"@ALPS_School","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alps.edu\/calendar\/","url":"https:\/\/alps.edu\/calendar\/","name":"Calendario - Escuela de idiomas ALPS","isPartOf":{"@id":"https:\/\/alps.edu\/#website"},"datePublished":"2020-07-28T19:55:43+00:00","dateModified":"2020-07-28T20:54:24+00:00","breadcrumb":{"@id":"https:\/\/alps.edu\/calendar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alps.edu\/calendar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alps.edu\/calendar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alps.edu\/"},{"@type":"ListItem","position":2,"name":"Calendar"}]},{"@type":"WebSite","@id":"https:\/\/alps.edu\/#website","url":"https:\/\/alps.edu\/","name":"ALPS Language School","description":"Clases de ingl\u00e9s en Seattle para adultos","publisher":{"@id":"https:\/\/alps.edu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alps.edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alps.edu\/#organization","name":"ALPS Language School","url":"https:\/\/alps.edu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/","url":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","contentUrl":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","width":256,"height":181,"caption":"ALPS Language School"},"image":{"@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ALPS.Language.School\/","https:\/\/x.com\/ALPS_School","https:\/\/www.linkedin.com\/school\/alps-language-school\/"]}]}},"_links":{"self":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/pages\/925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/comments?post=925"}],"version-history":[{"count":2,"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/pages\/925\/revisions"}],"predecessor-version":[{"id":931,"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/pages\/925\/revisions\/931"}],"wp:attachment":[{"href":"https:\/\/alps.edu\/es\/wp-json\/wp\/v2\/media?parent=925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}