{"id":707,"date":"2020-07-13T12:03:50","date_gmt":"2020-07-13T19:03:50","guid":{"rendered":"https:\/\/alps.edu\/?post_type=course&#038;p=707"},"modified":"2025-12-06T11:07:56","modified_gmt":"2025-12-06T19:07:56","slug":"paquete-intensivo-de-ingles-academico-ii","status":"publish","type":"course","link":"https:\/\/alps.edu\/es_es\/course\/academic-intensive-english-package-ii\/","title":{"rendered":"Paquete de ingl\u00e9s intensivo acad\u00e9mico 20"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"707\" class=\"elementor elementor-707\" data-elementor-post-type=\"course\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a031950 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a031950\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-151dfa9\" data-id=\"151dfa9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-215a41c elementor-widget elementor-widget-spacer\" data-id=\"215a41c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12a23f6 dce_masking-none elementor-widget elementor-widget-video\" data-id=\"12a23f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/zbwc9Q5OqXo?si=C9i0uZYu103SIwUe&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Shintaro-Interview.jpg&quot;,&quot;id&quot;:3013,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/alps.edu\/wp-content\/uploads\/2024\/08\/Shintaro-Interview.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aaa16d3 dce_masking-none elementor-widget elementor-widget-video\" data-id=\"aaa16d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/L6HqJFr1SD8?si=o3inkkN4mh1KI9aE&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Shintaro-Interview-Japanese.jpg&quot;,&quot;id&quot;:3014,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-no-translation=\"\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-aaa16d3{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b396d5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b396d5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fe87a3\" data-id=\"3fe87a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f5600c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5600c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7393986\" data-id=\"7393986\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"author":2,"featured_media":0,"template":"","visa":[16],"course_type":[7],"fees":[88],"class_list":["post-707","course","type-course","status-publish","hentry","visa-f-1-visa","course_type-full-time","fees-1525-4-weeks"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Academic Intensive English Package 20 - ALPS Language School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alps.edu\/es_es\/curso\/paquete-intensivo-de-ingles-academico-ii\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Academic Intensive English Package 20 - ALPS Language School\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alps.edu\/es_es\/curso\/paquete-intensivo-de-ingles-academico-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"ALPS Language School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ALPS.Language.School\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-06T19:07:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ALPS_School\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-intensive-english-package-ii\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-intensive-english-package-ii\\\/\",\"name\":\"Academic Intensive English Package 20 - ALPS Language School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\"},\"datePublished\":\"2020-07-13T19:03:50+00:00\",\"dateModified\":\"2025-12-06T19:07:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-intensive-english-package-ii\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alps.edu\\\/course\\\/academic-intensive-english-package-ii\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-intensive-english-package-ii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alps.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Academic Intensive English Package 20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"name\":\"ALPS Language School\",\"description\":\"Seattle English Classes for Adults\",\"publisher\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alps.edu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\",\"name\":\"ALPS Language School\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"contentUrl\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"width\":256,\"height\":181,\"caption\":\"ALPS Language School\"},\"image\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ALPS.Language.School\\\/\",\"https:\\\/\\\/x.com\\\/ALPS_School\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/alps-language-school\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paquete 20 de Ingl\u00e9s Acad\u00e9mico Intensivo - Escuela de Idiomas ALPS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alps.edu\/es_es\/curso\/paquete-intensivo-de-ingles-academico-ii\/","og_locale":"es_ES","og_type":"article","og_title":"Academic Intensive English Package 20 - ALPS Language School","og_url":"https:\/\/alps.edu\/es_es\/curso\/paquete-intensivo-de-ingles-academico-ii\/","og_site_name":"ALPS Language School","article_publisher":"https:\/\/www.facebook.com\/ALPS.Language.School\/","article_modified_time":"2025-12-06T19:07:56+00:00","twitter_card":"summary_large_image","twitter_site":"@ALPS_School","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alps.edu\/course\/academic-intensive-english-package-ii\/","url":"https:\/\/alps.edu\/course\/academic-intensive-english-package-ii\/","name":"Paquete 20 de Ingl\u00e9s Acad\u00e9mico Intensivo - Escuela de Idiomas ALPS","isPartOf":{"@id":"https:\/\/alps.edu\/#website"},"datePublished":"2020-07-13T19:03:50+00:00","dateModified":"2025-12-06T19:07:56+00:00","breadcrumb":{"@id":"https:\/\/alps.edu\/course\/academic-intensive-english-package-ii\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alps.edu\/course\/academic-intensive-english-package-ii\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alps.edu\/course\/academic-intensive-english-package-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alps.edu\/"},{"@type":"ListItem","position":2,"name":"Academic Intensive English Package 20"}]},{"@type":"WebSite","@id":"https:\/\/alps.edu\/#website","url":"https:\/\/alps.edu\/","name":"ALPS Language School","description":"Clases de ingl\u00e9s en Seattle para adultos","publisher":{"@id":"https:\/\/alps.edu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alps.edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/alps.edu\/#organization","name":"ALPS Language School","url":"https:\/\/alps.edu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/","url":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","contentUrl":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","width":256,"height":181,"caption":"ALPS Language School"},"image":{"@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ALPS.Language.School\/","https:\/\/x.com\/ALPS_School","https:\/\/www.linkedin.com\/school\/alps-language-school\/"]}]}},"_links":{"self":[{"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/course\/707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/types\/course"}],"author":[{"embeddable":true,"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":27,"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/course\/707\/revisions"}],"predecessor-version":[{"id":3716,"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/course\/707\/revisions\/3716"}],"wp:attachment":[{"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/media?parent=707"}],"wp:term":[{"taxonomy":"visa","embeddable":true,"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/visa?post=707"},{"taxonomy":"course_type","embeddable":true,"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/course_type?post=707"},{"taxonomy":"fees","embeddable":true,"href":"https:\/\/alps.edu\/es_es\/wp-json\/wp\/v2\/fees?post=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}