{"id":1996,"date":"2023-05-03T09:55:24","date_gmt":"2023-05-03T16:55:24","guid":{"rendered":"https:\/\/alps.edu\/?post_type=course&#038;p=1996"},"modified":"2023-05-23T14:07:34","modified_gmt":"2023-05-23T21:07:34","slug":"quartier-universitaire","status":"publish","type":"course","link":"https:\/\/alps.edu\/fr\/course\/academic-quarter\/","title":{"rendered":"Quartier acad\u00e9mique"},"content":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","visa":[16],"course_type":[7],"fees":[63],"class_list":["post-1996","course","type-course","status-publish","hentry","visa-f-1-visa","course_type-full-time","fees-63"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Academic Quarter<\/title>\n<meta name=\"description\" content=\"Combine small group classes and individualized private lessons to improve your English quickly. Focus on speaking and listening skills.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alps.edu\/fr\/cours\/quartier-universitaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Academic Quarter\" \/>\n<meta property=\"og:description\" content=\"Combine small group classes and individualized private lessons to improve your English quickly. Focus on speaking and listening skills.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alps.edu\/fr\/cours\/quartier-universitaire\/\" \/>\n<meta property=\"og:site_name\" content=\"ALPS Language School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ALPS.Language.School\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T21:07:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ALPS_School\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-quarter\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-quarter\\\/\",\"name\":\"Academic Quarter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\"},\"datePublished\":\"2023-05-03T16:55:24+00:00\",\"dateModified\":\"2023-05-23T21:07:34+00:00\",\"description\":\"Combine small group classes and individualized private lessons to improve your English quickly. Focus on speaking and listening skills.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-quarter\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alps.edu\\\/course\\\/academic-quarter\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/academic-quarter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alps.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Academic Quarter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"name\":\"ALPS Language School\",\"description\":\"Seattle English Classes for Adults\",\"publisher\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alps.edu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\",\"name\":\"ALPS Language School\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"contentUrl\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"width\":256,\"height\":181,\"caption\":\"ALPS Language School\"},\"image\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ALPS.Language.School\\\/\",\"https:\\\/\\\/x.com\\\/ALPS_School\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/alps-language-school\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quartier acad\u00e9mique","description":"Combinez des cours en petits groupes et des cours priv\u00e9s individualis\u00e9s pour am\u00e9liorer votre anglais rapidement. Concentrez-vous sur les comp\u00e9tences d&#039;expression et d&#039;\u00e9coute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alps.edu\/fr\/cours\/quartier-universitaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Academic Quarter","og_description":"Combine small group classes and individualized private lessons to improve your English quickly. Focus on speaking and listening skills.","og_url":"https:\/\/alps.edu\/fr\/cours\/quartier-universitaire\/","og_site_name":"ALPS Language School","article_publisher":"https:\/\/www.facebook.com\/ALPS.Language.School\/","article_modified_time":"2023-05-23T21:07:34+00:00","twitter_card":"summary_large_image","twitter_site":"@ALPS_School","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alps.edu\/course\/academic-quarter\/","url":"https:\/\/alps.edu\/course\/academic-quarter\/","name":"Quartier acad\u00e9mique","isPartOf":{"@id":"https:\/\/alps.edu\/#website"},"datePublished":"2023-05-03T16:55:24+00:00","dateModified":"2023-05-23T21:07:34+00:00","description":"Combinez des cours en petits groupes et des cours priv\u00e9s individualis\u00e9s pour am\u00e9liorer votre anglais rapidement. Concentrez-vous sur les comp\u00e9tences d&#039;expression et d&#039;\u00e9coute.","breadcrumb":{"@id":"https:\/\/alps.edu\/course\/academic-quarter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alps.edu\/course\/academic-quarter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alps.edu\/course\/academic-quarter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alps.edu\/"},{"@type":"ListItem","position":2,"name":"Academic Quarter"}]},{"@type":"WebSite","@id":"https:\/\/alps.edu\/#website","url":"https:\/\/alps.edu\/","name":"\u00c9cole de langues ALPS","description":"Cours d&#039;anglais \u00e0 Seattle pour adultes","publisher":{"@id":"https:\/\/alps.edu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alps.edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/alps.edu\/#organization","name":"\u00c9cole de langues ALPS","url":"https:\/\/alps.edu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/","url":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","contentUrl":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","width":256,"height":181,"caption":"ALPS Language School"},"image":{"@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ALPS.Language.School\/","https:\/\/x.com\/ALPS_School","https:\/\/www.linkedin.com\/school\/alps-language-school\/"]}]}},"_links":{"self":[{"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/course\/1996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/types\/course"}],"author":[{"embeddable":true,"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":2,"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/course\/1996\/revisions"}],"predecessor-version":[{"id":2126,"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/course\/1996\/revisions\/2126"}],"wp:attachment":[{"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/media?parent=1996"}],"wp:term":[{"taxonomy":"visa","embeddable":true,"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/visa?post=1996"},{"taxonomy":"course_type","embeddable":true,"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/course_type?post=1996"},{"taxonomy":"fees","embeddable":true,"href":"https:\/\/alps.edu\/fr\/wp-json\/wp\/v2\/fees?post=1996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}