{"id":190,"date":"2020-04-28T16:09:56","date_gmt":"2020-04-28T23:09:56","guid":{"rendered":"https:\/\/alps.edu\/?post_type=course&#038;p=190"},"modified":"2025-12-06T11:22:34","modified_gmt":"2025-12-06T19:22:34","slug":"%e0%b9%81%e0%b8%9e%e0%b9%87%e0%b8%84%e0%b9%80%e0%b8%81%e0%b8%88%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9%e0%b9%80%e0%b8%a3%e0%b9%88%e0%b8%87%e0%b8%a3","status":"publish","type":"course","link":"https:\/\/alps.edu\/th\/course\/general-intensive-english-package\/","title":{"rendered":"\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"190\" class=\"elementor elementor-190\" data-elementor-post-type=\"course\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-21da9f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21da9f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0997a86\" data-id=\"0997a86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e8ca03 dce_masking-none elementor-widget elementor-widget-video\" data-id=\"1e8ca03\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=jqkqnE--ylU&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Erick-Interview-1.jpg&quot;,&quot;id&quot;:3007,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/Erick-Interview-1.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"\u0e40\u0e25\u0e48\u0e19\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3a756f dce_masking-none elementor-widget elementor-widget-video\" data-id=\"a3a756f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=1WBm9nT3xzE&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Erick-Interview-Portuguese.jpg&quot;,&quot;id&quot;:3011,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-no-translation=\"\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-a3a756f{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"author":1,"featured_media":0,"template":"","visa":[16],"course_type":[7],"fees":[89],"class_list":["post-190","course","type-course","status-publish","hentry","visa-f-1-visa","course_type-full-time","fees-1385-4-weeks"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>General Intensive English Package - ALPS Language School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e23\u0e48\u0e07\u0e23\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General Intensive English Package - ALPS Language School\" \/>\n<meta property=\"og:description\" content=\"https:\/\/www.youtube.com\/watch?v=jqkqnE&#8211;ylUhttps:\/\/www.youtube.com\/watch?v=1WBm9nT3xzE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e23\u0e48\u0e07\u0e23\/\" \/>\n<meta property=\"og:site_name\" content=\"ALPS Language School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ALPS.Language.School\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-06T19:22:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ALPS_School\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/general-intensive-english-package\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/course\\\/general-intensive-english-package\\\/\",\"name\":\"General Intensive English Package - ALPS Language School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\"},\"datePublished\":\"2020-04-28T23:09:56+00:00\",\"dateModified\":\"2025-12-06T19:22:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/general-intensive-english-package\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alps.edu\\\/course\\\/general-intensive-english-package\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/general-intensive-english-package\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alps.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General Intensive English Package\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"name\":\"ALPS Language School\",\"description\":\"Seattle English Classes for Adults\",\"publisher\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alps.edu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\",\"name\":\"ALPS Language School\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"contentUrl\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"width\":256,\"height\":181,\"caption\":\"ALPS Language School\"},\"image\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ALPS.Language.School\\\/\",\"https:\\\/\\\/x.com\\\/ALPS_School\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/alps-language-school\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b - \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e23\u0e48\u0e07\u0e23\/","og_locale":"th_TH","og_type":"article","og_title":"General Intensive English Package - ALPS Language School","og_description":"https:\/\/www.youtube.com\/watch?v=jqkqnE&#8211;ylUhttps:\/\/www.youtube.com\/watch?v=1WBm9nT3xzE","og_url":"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e23\u0e48\u0e07\u0e23\/","og_site_name":"ALPS Language School","article_publisher":"https:\/\/www.facebook.com\/ALPS.Language.School\/","article_modified_time":"2025-12-06T19:22:34+00:00","twitter_card":"summary_large_image","twitter_site":"@ALPS_School","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alps.edu\/course\/general-intensive-english-package\/","url":"https:\/\/alps.edu\/course\/general-intensive-english-package\/","name":"\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b - \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","isPartOf":{"@id":"https:\/\/alps.edu\/#website"},"datePublished":"2020-04-28T23:09:56+00:00","dateModified":"2025-12-06T19:22:34+00:00","breadcrumb":{"@id":"https:\/\/alps.edu\/course\/general-intensive-english-package\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alps.edu\/course\/general-intensive-english-package\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alps.edu\/course\/general-intensive-english-package\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alps.edu\/"},{"@type":"ListItem","position":2,"name":"General Intensive English Package"}]},{"@type":"WebSite","@id":"https:\/\/alps.edu\/#website","url":"https:\/\/alps.edu\/","name":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","description":"\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e19\u0e0b\u0e35\u0e41\u0e2d\u0e15\u0e40\u0e17\u0e34\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48","publisher":{"@id":"https:\/\/alps.edu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alps.edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/alps.edu\/#organization","name":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","url":"https:\/\/alps.edu\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/","url":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","contentUrl":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","width":256,"height":181,"caption":"ALPS Language School"},"image":{"@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ALPS.Language.School\/","https:\/\/x.com\/ALPS_School","https:\/\/www.linkedin.com\/school\/alps-language-school\/"]}]}},"_links":{"self":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/types\/course"}],"author":[{"embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":27,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course\/190\/revisions"}],"predecessor-version":[{"id":3722,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course\/190\/revisions\/3722"}],"wp:attachment":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/media?parent=190"}],"wp:term":[{"taxonomy":"visa","embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/visa?post=190"},{"taxonomy":"course_type","embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course_type?post=190"},{"taxonomy":"fees","embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/fees?post=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}