{"id":232,"date":"2020-05-19T00:32:20","date_gmt":"2020-05-19T07:32:20","guid":{"rendered":"https:\/\/alps.edu\/?post_type=course&#038;p=232"},"modified":"2025-12-06T11:16:36","modified_gmt":"2025-12-06T19:16:36","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9e%e0%b8%b9%e0%b8%94%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%ad%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%82","status":"publish","type":"course","link":"https:\/\/alps.edu\/th\/course\/intensive-speaking-and-listening\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"232\" class=\"elementor elementor-232\" data-elementor-post-type=\"course\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ae859da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae859da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7f5afd\" data-id=\"e7f5afd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bd3465 dce_masking-none elementor-widget elementor-widget-video\" data-id=\"6bd3465\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/duYQawhc1D0?si=rEUaLXrDriKw1d52&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Sevval-Interview.jpg&quot;,&quot;id&quot;:3012,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/alps.edu\/wp-content\/uploads\/2024\/08\/Sevval-Interview.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"\u0e40\u0e25\u0e48\u0e19\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9708235 dce_masking-none elementor-widget elementor-widget-video\" data-id=\"9708235\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/dMK2TkOY1xE?si=J42g6ZL21RBxufHp&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Sevval-Interview-Turkish-1.jpg&quot;,&quot;id&quot;:3015,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-no-translation=\"\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-9708235{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"author":1,"featured_media":0,"template":"","visa":[],"course_type":[8],"fees":[90],"class_list":["post-232","course","type-course","status-publish","hentry","course_type-part-time","fees-780-4-weeks"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intensive Speaking &amp; Listening - ALPS Language School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intensive Speaking &amp; Listening - ALPS Language School\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\/\" \/>\n<meta property=\"og:site_name\" content=\"ALPS Language School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ALPS.Language.School\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-06T19:16:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ALPS_School\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/intensive-speaking-and-listening\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/course\\\/intensive-speaking-and-listening\\\/\",\"name\":\"Intensive Speaking & Listening - ALPS Language School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\"},\"datePublished\":\"2020-05-19T07:32:20+00:00\",\"dateModified\":\"2025-12-06T19:16:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/intensive-speaking-and-listening\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alps.edu\\\/course\\\/intensive-speaking-and-listening\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alps.edu\\\/course\\\/intensive-speaking-and-listening\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alps.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intensive Speaking &#038; Listening\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#website\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"name\":\"ALPS Language School\",\"description\":\"Seattle English Classes for Adults\",\"publisher\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alps.edu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#organization\",\"name\":\"ALPS Language School\",\"url\":\"https:\\\/\\\/alps.edu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"contentUrl\":\"https:\\\/\\\/alps.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/alps-logo.png\",\"width\":256,\"height\":181,\"caption\":\"ALPS Language School\"},\"image\":{\"@id\":\"https:\\\/\\\/alps.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ALPS.Language.School\\\/\",\"https:\\\/\\\/x.com\\\/ALPS_School\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/alps-language-school\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14 - \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\/","og_locale":"th_TH","og_type":"article","og_title":"Intensive Speaking & Listening - ALPS Language School","og_url":"https:\/\/alps.edu\/th\/\u0e04\u0e2d\u0e23\u0e4c\u0e2a\/\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\/","og_site_name":"ALPS Language School","article_publisher":"https:\/\/www.facebook.com\/ALPS.Language.School\/","article_modified_time":"2025-12-06T19:16:36+00:00","twitter_card":"summary_large_image","twitter_site":"@ALPS_School","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alps.edu\/course\/intensive-speaking-and-listening\/","url":"https:\/\/alps.edu\/course\/intensive-speaking-and-listening\/","name":"\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14 - \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","isPartOf":{"@id":"https:\/\/alps.edu\/#website"},"datePublished":"2020-05-19T07:32:20+00:00","dateModified":"2025-12-06T19:16:36+00:00","breadcrumb":{"@id":"https:\/\/alps.edu\/course\/intensive-speaking-and-listening\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alps.edu\/course\/intensive-speaking-and-listening\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alps.edu\/course\/intensive-speaking-and-listening\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alps.edu\/"},{"@type":"ListItem","position":2,"name":"Intensive Speaking &#038; Listening"}]},{"@type":"WebSite","@id":"https:\/\/alps.edu\/#website","url":"https:\/\/alps.edu\/","name":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","description":"\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e19\u0e0b\u0e35\u0e41\u0e2d\u0e15\u0e40\u0e17\u0e34\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48","publisher":{"@id":"https:\/\/alps.edu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alps.edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/alps.edu\/#organization","name":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 ALPS","url":"https:\/\/alps.edu\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/","url":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","contentUrl":"https:\/\/alps.edu\/wp-content\/uploads\/2020\/04\/alps-logo.png","width":256,"height":181,"caption":"ALPS Language School"},"image":{"@id":"https:\/\/alps.edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ALPS.Language.School\/","https:\/\/x.com\/ALPS_School","https:\/\/www.linkedin.com\/school\/alps-language-school\/"]}]}},"_links":{"self":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/types\/course"}],"author":[{"embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":25,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course\/232\/revisions"}],"predecessor-version":[{"id":3720,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course\/232\/revisions\/3720"}],"wp:attachment":[{"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"visa","embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/visa?post=232"},{"taxonomy":"course_type","embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/course_type?post=232"},{"taxonomy":"fees","embeddable":true,"href":"https:\/\/alps.edu\/th\/wp-json\/wp\/v2\/fees?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}